{"id":353,"date":"2022-01-25T14:32:46","date_gmt":"2022-01-25T13:32:46","guid":{"rendered":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/?p=353"},"modified":"2022-01-25T14:32:46","modified_gmt":"2022-01-25T13:32:46","slug":"spd-rheinhausen-mitte-ehrt-jubilare","status":"publish","type":"post","link":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/spd-rheinhausen-mitte-ehrt-jubilare\/","title":{"rendered":"SPD Rheinhausen-Mitte ehrt Jubilare"},"content":{"rendered":"\n<p>K\u00fcrzlich ehrte der SPD-Ortsverein Rheinhausen-Mitte, corona-bedingt\u00a0 nur in einer kleinen Runde, seine Jubilare.<br>Mit der Ehrung wurde die jeweilige 50-j\u00e4hrige Parteimitgliedschaft von Doris Rappold, Hans Medewitz und den Eheleuten Lieselotte und Helmut Weigelt gew\u00fcrdigt.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>&#8222;Mit ihrer langj\u00e4hrigen Mitgliedschaft haben Sie ein Zeichen f\u00fcr Solidarit\u00e4t und mehr soziale Gerechtigkeit in der Gesellschaft gesetzt.<br>Sie haben aktiv daran mitgewirkt, ein demokratisches und soziales Gemeinwesen aufzubauen und sich auch in schwierigen Zeiten nicht entmutigen lassen.&#8220;<\/p><cite>Dankesreden Dirk Smaczny, OV-Vorsitzender und Rainer Bischoff, MdL<\/cite><\/blockquote><\/figure>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/spd-rheinhausen-mitte.de\/wp-content\/uploads\/2022\/01\/Jubilarehrung-1-1-1024x768.jpg\" alt=\"\" class=\"wp-image-356\" srcset=\"https:\/\/spd-rheinhausen-mitte.de\/wp-content\/uploads\/2022\/01\/Jubilarehrung-1-1-1024x768.jpg 1024w, https:\/\/spd-rheinhausen-mitte.de\/wp-content\/uploads\/2022\/01\/Jubilarehrung-1-1-300x225.jpg 300w, https:\/\/spd-rheinhausen-mitte.de\/wp-content\/uploads\/2022\/01\/Jubilarehrung-1-1-768x576.jpg 768w, https:\/\/spd-rheinhausen-mitte.de\/wp-content\/uploads\/2022\/01\/Jubilarehrung-1-1-1536x1152.jpg 1536w, https:\/\/spd-rheinhausen-mitte.de\/wp-content\/uploads\/2022\/01\/Jubilarehrung-1-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>  von links: Ratsherr Ersin Erdal, OV-Vorsitzender Dirk Smaczny, Hans Medewitz, Ratsherr J\u00fcrgen Edel, Helmut Weigelt, Lieselotte Weigelt, Landtagsabgeordneter Rainer Bischoff, Doris Rappold. <\/figcaption><\/figure><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p> Ortsvereinsvorsitzender Dirk Smaczny und Landtagsabgeordneter Rainer Bischoff dankten den Jubilaren f\u00fcr ihre Treue zur Partei. Smaczny wies zudem darauf hin, dass die Werte, f\u00fcr die die Sozialdemokratie und somit auch die Jubilare so lange gek\u00e4mpft h\u00e4tten, auch heute wieder in Gefahr seien und verteidigt werden m\u00fcssten. Am Wirken der\u00a0 Jubilare machte Bischoff deutlich, wie wichtig jeder einzelne an seinem Platz f\u00fcr die Arbeit der Partei vor Ort sei. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p>Mit einem herzlichen Dankesch\u00f6n f\u00fcr jahrzehntelanges Engagement wurden den Jubilaren Ehrenurkunden, Ehrenzeichen sowie Pr\u00e4sente \u00fcberreicht.<\/p>\n\n\n\n<p>Herzliche Gr\u00fc\u00dfe<br>Dirk Smaczny<\/p>\n","protected":false},"excerpt":{"rendered":"<p>K\u00fcrzlich ehrte der SPD-Ortsverein Rheinhausen-Mitte, corona-bedingt\u00a0 nur in einer kleinen Runde, seine Jubilare.Mit der Ehrung wurde die jeweilige 50-j\u00e4hrige Parteimitgliedschaft<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[5],"tags":[12,11],"class_list":["post-353","post","type-post","status-publish","format-standard","hentry","category-themen-aus-der-vereinsarbeit","tag-ehrung","tag-jubilaeum"],"_links":{"self":[{"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/posts\/353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/comments?post=353"}],"version-history":[{"count":6,"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/posts\/353\/revisions"}],"predecessor-version":[{"id":361,"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/posts\/353\/revisions\/361"}],"wp:attachment":[{"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/media?parent=353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/categories?post=353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spd-rheinhausen-mitte.de\/willkommen\/wp-json\/wp\/v2\/tags?post=353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}